{"id":25493,"date":"2021-08-12T10:52:30","date_gmt":"2021-08-12T08:52:30","guid":{"rendered":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/noemi-camps-larxivament-provisional-del-cas-de-lescorxador-municipal-demostra-que-el-psoe-lha-gestionat-de-forma-transparent\/"},"modified":"2021-08-12T10:52:30","modified_gmt":"2021-08-12T08:52:30","slug":"noemi-camps-larxivament-provisional-del-cas-de-lescorxador-municipal-demostra-que-el-psoe-lha-gestionat-de-forma-transparent","status":"publish","type":"post","link":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/noemi-camps-larxivament-provisional-del-cas-de-lescorxador-municipal-demostra-que-el-psoe-lha-gestionat-de-forma-transparent\/","title":{"rendered":"Noem\u00ed Camps: \u201cL\u2019arxivament provisional del cas de l\u2019escorxador municipal demostra que el PSOE l\u2019ha gestionat de forma transparent\u201d"},"content":{"rendered":"<div class=\"row wpb_row row-fluid img_noticia\">\n<div class=\"wpb_column columns small-12 medium-12 thb-dark-column\">\n<div class=\"vc_column-inner  \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_single_image wpb_content_element vc_align_left\">\n<figure class=\"wpb_wrapper vc_figure\">\n<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"4905\" height=\"4806\" src=\"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-content\/uploads\/Noem&#xED;-Camps-min.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" \/><\/div>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row wpb_row row-fluid intro\">\n<div class=\"wpb_column columns small-12 medium-12 thb-dark-column\">\n<div class=\"vc_column-inner  \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element  \">\n<div class=\"wpb_wrapper\">\n<p>Noem\u00ed Camps ha fet un rep\u00e0s dels dos primers anys de mandat i defensa la gesti\u00f3 transparent del PSOE en el cas de l\u2019escorxador municipal<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<\/p><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row wpb_row row-fluid\">\n<div class=\"wpb_column columns small-12 medium-6 thb-dark-column\">\n<div class=\"vc_column-inner  \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element  \">\n<div class=\"wpb_wrapper\">\n<p>En una entrevista gravada de forma exclusiva per al canal audiovisual PSOE Menorca TV, la Secret\u00e0ria General del PSOE Ciutadella, Noem\u00ed Camps, fa una an\u00e0lisi de les pol\u00edtiques que s\u2019han posat en marxa des de l\u2019ajuntament durant els primers anys de mandat, reconeixent, per\u00f2, que \u201cla irrupci\u00f3 de la pand\u00e8mia ens ha fet canviar a tots les prioritats\u201d.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>No obstant aix\u00f2, \u201cal llarg d\u2019aquests dos primers anys, hem pogut fer realitat o iniciar alguns projectes fonamentals per a la ciutadania i el municipi, com la millora de les urbanitzacions, avan\u00e7ar en l\u2019amplicaci\u00f3 dels espais del geri\u00e0tric municipal o iniciar els tr\u00e0mits per a l\u2019escola de m\u00fasica, entre d\u2019altres\u201d.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>De tot aix\u00f2, Camps ha defensat que una de les fites sobre les quals se sent m\u00e9s satisfeta d\u2019haver contribu\u00eft a assolir sent regidora a l\u2019ajuntament, ha estat \u201cposar en marxa la dessaladora municipal, una reivindicaci\u00f3 hist\u00f2rica i demanda social que requeria d\u2019una soluci\u00f3 per millorar la gesti\u00f3 eficient dels recursos h\u00eddrics del poble\u201d.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<\/p><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column columns small-12 medium-6 thb-dark-column\">\n<div class=\"vc_column-inner  \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element  \">\n<div class=\"wpb_wrapper\">\n<p>Per altra banda, Camps tamb\u00e9 s\u2019ha pronunciat sobre la not\u00edcia de l\u2019arxivament provisional del cas l\u2019escorxador municipal, \u201cun desenlla\u00e7 que ten\u00edem clar des del Partit Socialista que havia de ser aquest\u201d, ha defensat. De fet, \u201cel PP \u00e9s el menys indicat per intentar implicar l\u2019ajuntament en q\u00fcestions de corrupci\u00f3, quan l\u2019her\u00e8ncia que els precedeix precisament no \u00e9s ni lloable ni transparent\u201d, ha criticat.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Quant a iniciatives en mat\u00e8ria tur\u00edstica, Camps ha valorat positivament la participaci\u00f3 de l\u2019ajuntament de Ciutadella a FITUR, \u201cun espai de participaci\u00f3 com\u00fa on vam poder promocionar el nostre municipi a trav\u00e9s de la campanya \u2018enjoy Ciutadella\u2019, tot amb l\u2019objectiu de situar Menorca com una destinaci\u00f3 segura i de qualitat\u201d.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Pel que fa a les imatges d\u2019aglomeracions de persones durant els dies de festa de Sant Joan, Camps ha reconegut que \u201cno vam ser capa\u00e7os de preveure la magnitud del que passaria, per\u00f2 consideram que el lideratge del consistori ha de ser m\u00e9s fort i contundent, millorant la coordinaci\u00f3 amb les altres administracions\u201d. En aquest sentit, \u201cja esteim immersos en la creaci\u00f3 de la junta municipal de Sant Joan, precisament per garantir aquesta relaci\u00f3 institucional i millorar aix\u00ed la gesti\u00f3 de les nostres festes de cara als propers anys\u201d.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<\/p><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&#013;<br \/>\nSource: Federaci\u00f3 de Menorca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noem\u00ed Camps ha fet un rep\u00e0s dels dos primers anys de mandat i defensa la gesti\u00f3 transparent del PSOE en el cas de l\u2019escorxador municipal\u00a0 En una entrevista gravada de forma exclusiva per al canal audiovisual PSOE Menorca TV, la Secret\u00e0ria General del PSOE Ciutadella, Noem\u00ed Camps, fa una an\u00e0lisi de les pol\u00edtiques que s\u2019han&hellip;<\/p>\n","protected":false},"author":1,"featured_media":25494,"comment_status":"false","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[84],"class_list":["post-25493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-federacio-de-menorca","tag-psib-psoe"],"_links":{"self":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/posts\/25493"}],"collection":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/comments?post=25493"}],"version-history":[{"count":0,"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/posts\/25493\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/media\/25494"}],"wp:attachment":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/media?parent=25493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/categories?post=25493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/tags?post=25493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}