{"id":26797,"date":"2023-11-27T12:27:06","date_gmt":"2023-11-27T10:27:06","guid":{"rendered":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/?p=26797"},"modified":"2023-11-27T12:28:23","modified_gmt":"2023-11-27T10:28:23","slug":"el-psoe-proposa-nou-mesures-per-a-millorar-la-transparencia-i-representativitat-a-lajuntament-des-migjorn","status":"publish","type":"post","link":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/el-psoe-proposa-nou-mesures-per-a-millorar-la-transparencia-i-representativitat-a-lajuntament-des-migjorn\/","title":{"rendered":"El PSOE proposa nou mesures per a millorar la transpar\u00e8ncia i representativitat a l\u2019Ajuntament des Migjorn"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"845\" height=\"1024\" src=\"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-content\/uploads\/IMG_2032-845x1024.jpg\" alt=\"\" class=\"wp-image-26803\" srcset=\"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-content\/uploads\/IMG_2032-845x1024.jpg 845w, https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-content\/uploads\/IMG_2032-248x300.jpg 248w, https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-content\/uploads\/IMG_2032-768x930.jpg 768w, https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-content\/uploads\/IMG_2032-300x363.jpg 300w, https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-content\/uploads\/IMG_2032-150x182.jpg 150w, https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-content\/uploads\/IMG_2032-600x727.jpg 600w, https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-content\/uploads\/IMG_2032-900x1090.jpg 900w, https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-content\/uploads\/IMG_2032-20x24.jpg 20w, https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-content\/uploads\/IMG_2032.jpg 1179w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><\/figure>\n\n\n\n<p>El Grup Municipal Socialista va registrar el passat mes d\u2019octubre una moci\u00f3 que ser\u00e0 debatuda en el ple de dia 30 de novembre sobre les mesures de transpar\u00e8ncia a l\u2019Ajuntament des Migjorn Gran. Per als socialistes, transpar\u00e8ncia \u00e9s imprescindible per al funcionament democr\u00e0tic del nostre ajuntament i cal implementar una s\u00e8rie de mesures per a millorar en aquest aspecte.<br><\/p>\n\n\n\n<p>Els regidors socialistes aprofiten per reclamar tota la documentaci\u00f3 que t\u00e9 demanada al consistori per a poder fer la feina d\u2019oposici\u00f3 i que no se li lliura amb els terminis que pertocaria. La darrera tanda de documents lliurats, per exemple, correspon a sol\u00b7licituds d\u2019informaci\u00f3 de feia m\u00e9s de vuit mesos. Els socialistes consideren que aquests retards dificulten la feina de control al govern de l\u2019Ajuntament i que vulnera l\u2019article 8 del Reglament Org\u00e0nic Municipal.<br><\/p>\n\n\n\n<p>El fet que l\u2019equip de govern no convidi als regidors de l\u2019oposici\u00f3 als actes institucionals tamb\u00e9 entra en contradicci\u00f3 amb el Reglament Org\u00e0nic, ja que dificulta el compliment de l\u2019article 7.2. A m\u00e9s, l\u2019oposici\u00f3 tamb\u00e9 demana que es gravi en v\u00eddeo i es retransmeti les sessions plen\u00e0ries perqu\u00e8 la ciutadania pugui seguir-les i estar informada, com es fa als altres ajuntaments de l\u2019illa de Menorca.<br><\/p>\n\n\n\n<p>Aquesta \u00e9s la llista de mesures que proposa el PSOE Migjorn per a la millora de la transpar\u00e8ncia i la representativitat de l\u2019Ajuntament des Migjorn Gran:<br><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Publicar el Reglament Org\u00e0nic Municipal a la p\u00e0gina web de l\u2019Ajuntament i fer entrega d\u2019una c\u00f2pia a cada regidor.<\/li><li>La batlia entregar\u00e0 tota la documentaci\u00f3 que el Grup de l\u2019oposici\u00f3 ha demanat per registre d\u2019entrada en els darrers mesos, en compliment de l\u2019Article 8 del Reglament Org\u00e0nic. D\u2019ara endavant, la batlia es compromet a fer arribar tota la documentaci\u00f3 requerida al grup de l\u2019oposici\u00f3 complint els terminis legals.\u00a0<\/li><li>L\u2019equip de govern garantir\u00e0 la representativitat visible dels regidors de l\u2019oposici\u00f3 en els actes p\u00fablics mitjan\u00e7ant invitacions, complint aix\u00ed amb Article 7.2 del Reglament Org\u00e0nic.<\/li><li>L\u2019equip de govern posar\u00e0 en marxa un sistema per a gravar en v\u00eddeo les sessions plen\u00e0ries i emetre-les en directe a trav\u00e9s de la web de l\u2019Ajuntament o d\u2019una xarxa social.<\/li><li>L\u2019Ajuntament crear\u00e0 correus electr\u00f2nics de la corporaci\u00f3 per als regidors de l\u2019oposici\u00f3 i publicar\u00e0 les seves adreces a l\u2019apartat de la plana web corresponent.<\/li><li>L\u2019Ajuntament publicar\u00e0 a la plana web les declaracions de b\u00e9ns de tots els membres de la Corporaci\u00f3.<\/li><li>L\u2019Ajuntament actualitzar\u00e0 els apartats de la plana web \u201cAssociacions des Migjorn Gran\u201d, \u201cEscola Municipal de M\u00fasica\u201d, \u201cPunt d\u2019Informaci\u00f3 Juvenil\u201d, \u201cCasal de Joves\u201d i \u201cInstal\u00b7lacions i Activitats Esportives\u201d.<\/li><li>Publicar, amb la periodicitat acordada per Plenari, el Butllet\u00ed d\u2019informaci\u00f3 municipal que inclogui un espai reservat a l\u2019oposici\u00f3, complint aix\u00ed amb els Articles 69 i 70 del Reglament Org\u00e0nic.<\/li><li>Recuperar la Junta de Govern Local, que tot i no ser un \u00f2rgan obligatori per als municipis de menys de 5000 habitants, ha existit a l\u2019Ajuntament des Migjorn entre els anys 2007 i 2017.<\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>El Grup Municipal Socialista va registrar el passat mes d\u2019octubre una moci\u00f3 que ser\u00e0 debatuda en el ple de dia 30 de novembre sobre les mesures de transpar\u00e8ncia a l\u2019Ajuntament des Migjorn Gran. Per als socialistes, transpar\u00e8ncia \u00e9s imprescindible per al funcionament democr\u00e0tic del nostre ajuntament i cal implementar una s\u00e8rie de mesures per a&hellip;<\/p>\n","protected":false},"author":7,"featured_media":26803,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[97],"tags":[],"class_list":["post-26797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-es-migjorn"],"_links":{"self":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/posts\/26797"}],"collection":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/comments?post=26797"}],"version-history":[{"count":0,"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/posts\/26797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/media\/26803"}],"wp:attachment":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/media?parent=26797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/categories?post=26797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/migjorn\/wp-json\/wp\/v2\/tags?post=26797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}