{"id":26060,"date":"2021-12-14T10:11:00","date_gmt":"2021-12-14T08:11:00","guid":{"rendered":"http:\/\/www.psib-psoe.org\/menorca\/?p=26060"},"modified":"2022-05-13T12:09:53","modified_gmt":"2022-05-13T10:09:53","slug":"susana-mora-ha-estat-proclamada-secretaria-general-del-psoe-menorca","status":"publish","type":"post","link":"https:\/\/www.psib-psoe.org\/menorca\/susana-mora-ha-estat-proclamada-secretaria-general-del-psoe-menorca\/","title":{"rendered":"Susana Mora ha estat proclamada secret\u00e0ria general del PSOE Menorca"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row el_class=&#8221;img_noticia&#8221;][vc_column][vc_single_image image=&#8221;26051&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row el_class=&#8221;intro&#8221;][vc_column][vc_column_text]La seva candidatura ha cobert el percentatge d&#8217;avals necessaris per fer-la efectiva, el qual se situa entre el 12% i el 15%<\/p>\n<p>La pon\u00e8ncia marc es troba en fase de revisi\u00f3 i aportacions per part de les agrupacions locals<span class=\"Apple-converted-space\">\u00a0<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text]Susana Mora ha estat proclamada secret\u00e0ria general del PSOE Menorca, despr\u00e9s que la Comissi\u00f3 d&#8217;\u00c8tica i Garanties del PSIB hagi validat els avals aportats per a la seva candidatura. En aquest cas, Mora ha presentat el m\u00e0xim d&#8217;avals necessaris establert, des de la seva darrera modificaci\u00f3 dels Estatuts Federals, el passat mes de novembre, entre el 12% i el 15% de la milit\u00e0ncia de l&#8217;illa. D&#8217;aquesta manera, s&#8217;ha concl\u00f2s el proc\u00e9s de prim\u00e0ries iniciat pel 14\u00e8 Congr\u00e9s de la Federaci\u00f3 Socialista de Menorca.<\/p>\n<p>Aquesta \u00e9s la segona vegada que Susana Mora reedita el c\u00e0rrec, iniciant aix\u00ed el segon mandat consecutiu, despr\u00e9s del de 2017-2021. &#8220;Suposa un enorme orgull i responsabilitat seguir liderant un Partit que sap estar a l&#8217;al\u00e7ada de cada situaci\u00f3, que prioritza una major protecci\u00f3 social i que camina cap a la recuperaci\u00f3 econ\u00f2mica de la seva societat&#8221;, ha defensat la Secret\u00e0ria General.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>La socialista ha volgut afegir que aquesta proclamaci\u00f3 definitiva &#8220;ha estat gr\u00e0cies, com no pot ser d&#8217;altra manera, a l&#8217;empenta i estal\u00f3 d&#8217;una milit\u00e0ncia incondicional que ha estat sempre al costat meu i al costat de tot l&#8217;equip que m&#8217;ha acompanyat al llarg d&#8217;aquests 4 anys. Ara toca seguir un cam\u00ed comen\u00e7at, un cam\u00ed que, sense la for\u00e7a de cada persona que forma aquest partit, avan\u00e7ar no seria possible&#8221;.<span class=\"Apple-converted-space\">\u00a0<\/span>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]Per altra banda, el document de pon\u00e8ncia marc, que ha de regir les propostes pol\u00edtiques dels propers 4 anys, es troba en fase de revisi\u00f3 i aportacions. Les agrupacions locals tenen un termini fins el 19 de desembre per celebrar les seves assemblees, on es podran presentar esmenes al document. Tamb\u00e9 serviran per elegir els delegats i les delegades que les defensaran al Congr\u00e9s Insular, els dies 22 i 23 de gener, a la Sala Albert Camus de Sant Llu\u00eds.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Amb tot, la Federaci\u00f3 Socialista de Menorca viu un moment intern intens marcat per la celebraci\u00f3 del seu 14\u00e8 Congr\u00e9s. Aquesta cita insular posar\u00e0 l&#8217;accent en la participaci\u00f3 i di\u00e0leg de tota la milit\u00e0ncia, amb una programaci\u00f3 dirigida especialment al debat d&#8217;idees i propostes. Tot amb l&#8217;objectiu de seguir nodrint el projecte socialista a totes les institucions p\u00fabliques per tal de reeditar la vict\u00f2ria electoral de 2019.<span class=\"Apple-converted-space\">\u00a0<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=SkGhUoTujBE&amp;t=1s&#8221;][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row el_class=&#8221;img_noticia&#8221;][vc_column][vc_single_image image=&#8221;26051&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row el_class=&#8221;intro&#8221;][vc_column][vc_column_text]La seva candidatura ha cobert el percentatge d&#8217;avals necessaris per fer-la efectiva, el qual se situa entre el 12% i el 15% La pon\u00e8ncia marc es troba en fase de revisi\u00f3 i aportacions per part de les agrupacions locals\u00a0[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text]Susana Mora ha estat proclamada secret\u00e0ria general del PSOE Menorca, despr\u00e9s que&hellip;<\/p>\n","protected":false},"author":6,"featured_media":26051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,1,92],"tags":[],"class_list":["post-26060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-federacio-de-menorca","category-federacio-de-menorca-portada","category-portada"],"_links":{"self":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/posts\/26060"}],"collection":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/comments?post=26060"}],"version-history":[{"count":0,"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/posts\/26060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/media\/26051"}],"wp:attachment":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/media?parent=26060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/categories?post=26060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/tags?post=26060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}