{"id":27422,"date":"2026-05-08T13:37:35","date_gmt":"2026-05-08T11:37:35","guid":{"rendered":"https:\/\/www.psib-psoe.org\/menorca\/?p=27422"},"modified":"2026-05-08T13:37:38","modified_gmt":"2026-05-08T11:37:38","slug":"el-psoe-menorca-exigeix-duplicar-fins-als-10-milions-deuros-la-partida-de-la-llei-reserva-de-biosfera","status":"publish","type":"post","link":"https:\/\/www.psib-psoe.org\/menorca\/el-psoe-menorca-exigeix-duplicar-fins-als-10-milions-deuros-la-partida-de-la-llei-reserva-de-biosfera\/","title":{"rendered":"El PSOE Menorca exigeix duplicar fins als 10 milions d&#8217;euros la partida de la Llei Reserva de Biosfera"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.psib-psoe.org\/menorca\/wp-content\/uploads\/DSC02114-1024x683.jpg\" alt=\"\" class=\"wp-image-27423\" srcset=\"https:\/\/www.psib-psoe.org\/menorca\/wp-content\/uploads\/DSC02114-1024x683.jpg 1024w, https:\/\/www.psib-psoe.org\/menorca\/wp-content\/uploads\/DSC02114-300x200.jpg 300w, https:\/\/www.psib-psoe.org\/menorca\/wp-content\/uploads\/DSC02114-768x512.jpg 768w, https:\/\/www.psib-psoe.org\/menorca\/wp-content\/uploads\/DSC02114-1536x1024.jpg 1536w, https:\/\/www.psib-psoe.org\/menorca\/wp-content\/uploads\/DSC02114-2048x1365.jpg 2048w, https:\/\/www.psib-psoe.org\/menorca\/wp-content\/uploads\/DSC02114-150x100.jpg 150w, https:\/\/www.psib-psoe.org\/menorca\/wp-content\/uploads\/DSC02114-600x400.jpg 600w, https:\/\/www.psib-psoe.org\/menorca\/wp-content\/uploads\/DSC02114-900x600.jpg 900w, https:\/\/www.psib-psoe.org\/menorca\/wp-content\/uploads\/DSC02114-20x13.jpg 20w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>El secretari general del PSOE Menorca, Pepe Mercadal, i el diputat Marc Pons han exigit aquest mat\u00ed que l\u2019import que rep Menorca a trav\u00e9s de la Llei Reserva de Biosfera es dupliqui fins als 10 milions d\u2019euros, de la mateixa manera que el Govern auton\u00f2mic vol fer amb l\u2019aportaci\u00f3 per Palma a trav\u00e9s de la Llei de Capitalitat.<\/p>\n\n\n\n<p>Els socialistes han recordat que l\u2019any 2023 es va aprovar la Llei Reserva de Biosfera de Menorca, una normativa que incorporava una partida espec\u00edfica de 5 milions d\u2019euros per a l\u2019illa. Aquesta partida se sumava a altres vies de finan\u00e7ament que rep el Consell Insular procedents del Govern auton\u00f2mic, com ara l&#8217;ITS. En aquest sentit, el PSOE ha recordat que Menorca rep aproximadament el 12% del total dels fons de l\u2019Impost de Turisme Sostenible (ITS) de les Illes Balears, un percentatge acordat durant l\u2019anterior etapa de govern progresssita.<\/p>\n\n\n\n<p>Els socialistes denuncien que, quan el PP va arribar al govern insular el 2023, el president Vilafranca va acceptar que els 5 milions d\u2019euros de la Llei Reserva de Biosfera quedassin integrats dins el repartiment ordinari de l\u2019ITS. \u201cA la pr\u00e0ctica, Menorca ja no rep aquests cinc milions com una aportaci\u00f3 extraordin\u00e0ria, perqu\u00e8 passen a computar dins el 12% habitual dels fons ITS. Va ser un engany del Govern de Marga Prohens i una acotada de cap de Vilafranca\u201d, ha criticat Mercadal.<\/p>\n\n\n\n<p>Ara, tres anys despr\u00e9s, el PSOE Menorca assenyala que el Govern auton\u00f2mic vol duplicar l\u2019aportaci\u00f3 que la Llei de Capitalitat preveu per a l\u2019Ajuntament de Palma, passant dels 30 als 60 milions d\u2019euros anuals.<\/p>\n\n\n\n<p>Davant aquest escenari, els socialistes exigeixen al president del Consell Insular que \u201cno torni a acotar el cap\u201d i que \u201caprofiti aquesta oportunitat\u201d per reclamar dues q\u00fcestions fonamentals: primer, que els recursos derivats de la Llei Reserva de Biosfera tenguin una partida pr\u00f2pia i diferenciada de l\u2019ITS i, segon, que si es duplica l\u2019aportaci\u00f3 a l\u2019Ajuntament de Palma tamb\u00e9 es dupliqui el que rep Menorca fins als 10 milions d\u2019euros anuals.<\/p>\n\n\n\n<p>El diputat Marc Pons ha avan\u00e7at que \u201cpresentarem una esmena a la proposta de llei del Govern per incrementar de 5 a 10 milions l\u2019aportaci\u00f3 que ha de rebre Menorca i demanam als altres partits que ens donin suport\u201d.<\/p>\n\n\n\n<p>Per tant, els socialistes han insistit que &#8220;si la modificaci\u00f3 de la llei de capitalitat es pren en consideraci\u00f3 el pr\u00f2xim dimarts en el Parlament de les Illes Balears, i en conseq\u00fc\u00e8ncia s&#8217;inicia la seva tramitaci\u00f3 en el Parlament, els diputats menorquins del PSIB-PSOE presentarem l&#8217;esmena per tal de garantir l&#8217;arribada dels 10 milions d&#8217;euros al Consell de Menorca&#8221;.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El secretari general del PSOE Menorca, Pepe Mercadal, i el diputat Marc Pons han exigit aquest mat\u00ed que l\u2019import que rep Menorca a trav\u00e9s de la Llei Reserva de Biosfera es dupliqui fins als 10 milions d\u2019euros, de la mateixa manera que el Govern auton\u00f2mic vol fer amb l\u2019aportaci\u00f3 per Palma a trav\u00e9s de la&hellip;<\/p>\n","protected":false},"author":6,"featured_media":27423,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,1,92],"tags":[],"class_list":["post-27422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-federacio-de-menorca","category-federacio-de-menorca-portada","category-portada"],"_links":{"self":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/posts\/27422"}],"collection":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/comments?post=27422"}],"version-history":[{"count":1,"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/posts\/27422\/revisions"}],"predecessor-version":[{"id":27424,"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/posts\/27422\/revisions\/27424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/media\/27423"}],"wp:attachment":[{"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/media?parent=27422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/categories?post=27422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psib-psoe.org\/menorca\/wp-json\/wp\/v2\/tags?post=27422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}